{"id":1223,"date":"2009-06-19T15:39:47","date_gmt":"2009-06-19T23:39:47","guid":{"rendered":"http:\/\/steve.cooleysekula.net\/blog\/wp-content\/uploads\/2009\/06\/img00072-20090618-1345.jpg"},"modified":"2009-06-19T15:39:47","modified_gmt":"2009-06-19T23:39:47","slug":"img00072-20090618-1345","status":"inherit","type":"attachment","link":"https:\/\/steve.cooleysekula.net\/blog\/2009\/06\/19\/disclosed-location\/img00072-20090618-1345\/","title":{"rendered":"img00072-20090618-1345"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-1223","attachment","type-attachment","status-inherit","czr-hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/steve.cooleysekula.net\/blog\/wp-content\/uploads\/2009\/06\/img00072-20090618-1345.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/steve.cooleysekula.net\/blog\/wp-content\/uploads\/2009\/06\/img00072-20090618-1345-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/steve.cooleysekula.net\/blog\/wp-content\/uploads\/2009\/06\/img00072-20090618-1345-300x225.jpg 300w, https:\/\/steve.cooleysekula.net\/blog\/wp-content\/uploads\/2009\/06\/img00072-20090618-1345.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1200,"hwstring_small":"height='96' width='128'","file":"\/net\/web\/apache\/www\/blogs\/steve\/taomph\/wp-content\/uploads\/2009\/06\/img00072-20090618-1345.jpg","sizes":{"thumbnail":{"file":"img00072-20090618-1345-150x150.jpg","width":150,"height":150,"source_url":"https:\/\/steve.cooleysekula.net\/blog\/wp-content\/uploads\/2009\/06\/img00072-20090618-1345-150x150.jpg"},"medium":{"file":"img00072-20090618-1345-300x225.jpg","width":300,"height":225,"source_url":"https:\/\/steve.cooleysekula.net\/blog\/wp-content\/uploads\/2009\/06\/img00072-20090618-1345-300x225.jpg"},"full":{"file":"img00072-20090618-1345.jpg","width":1600,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/steve.cooleysekula.net\/blog\/wp-content\/uploads\/2009\/06\/img00072-20090618-1345.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"BlackBerry 9000","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":1221,"source_url":"https:\/\/steve.cooleysekula.net\/blog\/wp-content\/uploads\/2009\/06\/img00072-20090618-1345.jpg","_links":{"self":[{"href":"https:\/\/steve.cooleysekula.net\/blog\/wp-json\/wp\/v2\/media\/1223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/steve.cooleysekula.net\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/steve.cooleysekula.net\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/steve.cooleysekula.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/steve.cooleysekula.net\/blog\/wp-json\/wp\/v2\/comments?post=1223"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1221,"href":"https:\/\/steve.cooleysekula.net\/blog\/wp-json\/wp\/v2\/posts\/1221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}